{"id":6660,"date":"2016-09-14T13:12:27","date_gmt":"2016-09-14T13:12:27","guid":{"rendered":"http:\/\/ctbe.cnpem.br\/?p=6660"},"modified":"2016-09-14T13:12:27","modified_gmt":"2016-09-14T13:12:27","slug":"workshop-second-generation-bioethanol-2016","status":"publish","type":"post","link":"https:\/\/lnbr.cnpem.br\/en\/workshop-second-generation-bioethanol-2016\/","title":{"rendered":"Workshop on Second Generation Bioethanol 2016"},"content":{"rendered":"<p class=\"x_MsoNormal\"><a href=\"http:\/\/pages.cnpem.br\/2gbioethanol\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" data-src=\"https:\/\/lnbr.cnpem.br\/wp-content\/uploads\/2016\/09\/2g-workshop.jpg\" class=\"alignnone wp-image-6671 size-full lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"testeira 2g bioethanol workshop\" width=\"818\" height=\"180\" \/><noscript><img decoding=\"async\" class=\"alignnone wp-image-6671 size-full\" src=\"https:\/\/lnbr.cnpem.br\/wp-content\/uploads\/2016\/09\/2g-workshop.jpg\" alt=\"testeira 2g bioethanol workshop\" width=\"818\" height=\"180\"><\/noscript><\/a><\/p>\n<p class=\"x_MsoNormal\">O Laborat\u00f3rio Nacional de Ci\u00eancia e Tecnologia do Bioetanol (CTBE) promove nos dias 30 de novembro e 1 de dezembro o\u00a0<strong>\u201cWorkshop on Second Generation Bioethanol 2016\u201d<\/strong> . O evento tem como objetivo discutir temas relacionados \u00e0 produ\u00e7\u00e3o de etanol 2G e outros produtos a partir de biomassa vegetal. Neste ano, os seguintes t\u00f3picos ser\u00e3o abordados:<\/p>\n<p class=\"x_MsoNormal\">I) Sistemas enzim\u00e1ticos para degrada\u00e7\u00e3o de material lignocelul\u00f3sico;<br \/>\nII) Sistemas microbianos para produ\u00e7\u00e3o de enzimas, biocombust\u00edveis e blocos qu\u00edmicos;<br \/>\nIII) Biomassa e biorrefinarias;<br \/>\nIV) Biocombust\u00edvel e ind\u00fastria.<\/p>\n<p class=\"x_MsoNormal\">Os interessados em participar do Workshop podem se inscrever at\u00e9 \u00a016 de outubro de 2016. Devido ao n\u00famero limitado de vagas, ser\u00e1 feita uma etapa de sele\u00e7\u00e3o dos inscritos com posterior confirma\u00e7\u00e3o da efetiva\u00e7\u00e3o da inscri\u00e7\u00e3o.<\/p>\n<p class=\"x_MsoNormal\"><strong>Inscreva-se aqui:\u00a0<a href=\"http:\/\/pages.cnpem.br\/2gbioethanol\/registration-2\/\">http:\/\/pages.cnpem.br\/2gbioethanol\/registration-2\/<\/a><\/strong><\/p>\n<p class=\"x_MsoNormal\">\n<p class=\"x_MsoNormal\">\n<p class=\"x_MsoNormal\">\n<p class=\"x_MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<p>O Laborat\u00f3rio Nacional de Ci\u00eancia e Tecnologia do Bioetanol (CTBE) promove nos dias 30 de novembro e 1 de dezembro o\u00a0\u201cWorkshop on Second Generation Bioethanol 2016\u201d . O evento tem como objetivo discutir temas relacionados \u00e0 produ\u00e7\u00e3o de etanol 2G e outros produtos a partir de biomassa vegetal. Neste ano, os seguintes t\u00f3picos ser\u00e3o abordados:&hellip;<\/p>\n","protected":false},"author":3,"featured_media":6675,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[88],"tags":[112,145,245,269],"class_list":["post-6660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-bioetanol","tag-ctbe","tag-second-generation","tag-workshop","category-88","description-off"],"acf":[],"_links":{"self":[{"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/posts\/6660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=6660"}],"version-history":[{"count":0,"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/posts\/6660\/revisions"}],"wp:attachment":[{"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=6660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=6660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lnbr.cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=6660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}